{"id":71605,"date":"2026-07-15T09:17:00","date_gmt":"2026-07-15T12:17:00","guid":{"rendered":"https:\/\/festivaldevitoria.com.br\/33fv\/?p=71605"},"modified":"2026-07-14T14:44:30","modified_gmt":"2026-07-14T17:44:30","slug":"10a-mostra-nacional-de-videoclipes-reune-mais-de-20-producoes-e-escancara-a-criatividade-brasileira","status":"publish","type":"post","link":"https:\/\/festivaldevitoria.com.br\/33fv\/2026\/07\/15\/10a-mostra-nacional-de-videoclipes-reune-mais-de-20-producoes-e-escancara-a-criatividade-brasileira\/","title":{"rendered":"10\u00aa Mostra Nacional de Videoclipes re\u00fane mais de 20 produ\u00e7\u00f5es e escancara a criatividade brasileira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>10\u00aa Mostra Nacional de Videoclipes<\/strong>, que ser\u00e1 realizada no dia 22 de julho, na <strong>Sala Marien Calixte <\/strong>(Sesc Gl\u00f3ria), durante o <strong>33\u00ba Festival de Cinema de Vit\u00f3ria<\/strong>, re\u00fane 20 videoclipes de diversos estados brasileiros. O FCV \u00e9 um dos poucos eventos audiovisuais do pa\u00eds a incluir uma janela competitiva exclusiva para videoclipes em seu circuito, consolidando a mostra como um territ\u00f3rio de mem\u00f3ria e resist\u00eancia do formato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os\u00a0 <strong><a href=\"https:\/\/festivaldevitoria.com.br\/33fv\/curadoria\/\" data-type=\"link\" data-id=\"https:\/\/festivaldevitoria.com.br\/33fv\/curadoria\/\">curadores da mostra<\/a><\/strong>, Suellen Vasconcelos e V\u00edtor B\u00farigo, destacam que a Mostra Nacional de Videoclipes, ao longo desses 10 anos, apresentou &#8220;um retrato desta arte que integra m\u00fasica e imagens em movimento&#8221;. Isso abriu caminho para que a pr\u00f3xima gera\u00e7\u00e3o \u201cflores\u00e7a em talento e ousadia, afirmando nossa identidade e valor, celebrando e fortalecendo nossa cultura&#8221;. Em rela\u00e7\u00e3o \u00e0 sele\u00e7\u00e3o de 2026, eles afirmam que\u00a0 as produ\u00e7\u00f5es escolhidas seguem &#8220;criando mem\u00f3rias a partir de obras que escancaram nossa cor, nosso ch\u00e3o e nossos sonhos&#8221;.\u00a0<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong>CAPIXABAS EM DESTAQUE<\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">A produ\u00e7\u00e3o capixaba marca presen\u00e7a com obras que apresentam narrativas consistentes em t\u00e9cnica, conceito e ponto de vista, como <strong>At\u00e9<\/strong> <em>(foto abaixo)<\/em>, dirigido por Victorhugo Amorim, Taciano Faccini e Gabrielle Nalli, do cantor Ronnie Silveira; <strong>Fino Prazer<\/strong>, dirigido por Tati Rabelo, da cantora Elo\u00e1 Puri; e <strong>Filtro<\/strong>, dirigido por Rayan Casagrande e Vinicius Caus, da banda Inseton.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Ate-1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-71610\" srcset=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Ate-1-1-980x653.jpg 980w, https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Ate-1-1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outros clipes capixabas entregam &#8220;o frescor e o risco da novidade&#8221;, como <strong>Tela Viva<\/strong>, dirigido por Rafael Sandim, do cantor Nobat, que constr\u00f3i um manifesto po\u00e9tico sobre reaprender a olhar para al\u00e9m das telas; <strong>Dist\u00e2ncia<\/strong>, dirigido por Daniel Bones, da banda Laika no Espa\u00e7o, um drama LGBT \u00edntimo sobre o momento exato em que o amor come\u00e7a a faltar oxig\u00eanio; <strong>A Presa<\/strong>, dirigido por Tommy Bellone e Julio Camelo, da banda Big River, gravado nos confins de S\u00e3o Mateus com refer\u00eancias de faroeste; <strong>T\u00f4 Ligando Pra Nada<\/strong>, dirigido por Enzo Rodrigues, da cantora Jessica Roberts, que celebra a vida com amigos em um momento de reflex\u00e3o; <strong>Sozinho Numa Bike Pra 2<\/strong>, dirigido por Carlo de C\u00e1sula, do artista cas\u00fc.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong>NORDESTE EM PROFUS\u00c3O<\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">De Sergipe, temos <strong>Epopeia de uma vida feliz<\/strong>, dirigido por Douglas Barros, do cantor Luno Torres, que acompanha a intimidade de um casal de dois homens que encontra no simples a pot\u00eancia do amor. J\u00e1 <strong>Hist\u00f3rias Perif\u00e9ricas<\/strong>, dirigido por Luan Allen, da cantora Priscila Neres, exalta as periferias com sensibilidade entre imagens do territ\u00f3rio e a for\u00e7a da palavra cantada, transformando o cotidiano perif\u00e9rico em pot\u00eancia est\u00e9tica, pol\u00edtica e cultural.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Cana-Queimada-de-Desejos-1-1-1024x681.jpg\" alt=\"\" class=\"wp-image-71611\" srcset=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Cana-Queimada-de-Desejos-1-1-980x652.jpg 980w, https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Cana-Queimada-de-Desejos-1-1-480x319.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Coco do Recado<\/strong>, dirigido por Clara Campos e Bianca Bomfim, da dupla Christine Valen\u00e7a &amp; Caetana, materializa o imagin\u00e1rio do Nordeste atrav\u00e9s do carnaval de Olinda em pel\u00edcula 16mm, com figuras como o Homem da Meia-Noite, Caboclos de Lan\u00e7a, La Ursa e Boizinhos. J\u00e1 <strong>Cana Queimada de Desejos<\/strong> <em>(foto acima)<\/em>, dirigido por Ricardo S\u00e9kula e S\u00e1vio Sabi\u00e1, do cantor S\u00e1vio Sabi\u00e1, registra a trajet\u00f3ria de um artista LGBTQIAPN+ da cultura popular da Zona da Mata Norte pernambucana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A noite \u00e9 o cen\u00e1rio tropical do videoclipe baiano <strong>Paladar<\/strong>, dirigido por Andr\u00e9 Castro Neto e Sthel\u00f4, da cantora Sthel\u00f4, que explora o desejo como algo estrangeiro em n\u00f3s. <strong>Monalisa<\/strong>, dirigido por Lucas S\u00e1, da multiartista maranhense Frimes, com humor e deboche, conta a hist\u00f3ria de uma maldi\u00e7\u00e3o evocada num roubo da Mona Lisa no museu do Louvre.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong><strong>ANCESTRALIDADE, JUVENTUDE E RESIST\u00caNCIA<\/strong><\/strong><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heran\u00e7a<\/strong>, dirigido por Keila-Sankofa, da artista Rafa Mili\u00e3o feat. M\u00e1rcia Siqueira, re\u00fane mulheres negras e ind\u00edgenas da Amaz\u00f4nia em uma cria\u00e7\u00e3o coletiva in\u00e9dita, propondo um mergulho nas \u00e1guas como forma de reconex\u00e3o com a ancestralidade. <strong>Astro Rei<\/strong>, dirigido por Gabriel Uchida, da cantora Gabri\u00ea, gravado em Porto Velho, celebra o corpo e o pertencimento, transformando o sol em s\u00edmbolo de for\u00e7a, perman\u00eancia e cura.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Quase-te-esqueci-2-1024x576.png\" alt=\"\" class=\"wp-image-71612\" srcset=\"https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Quase-te-esqueci-2-980x551.png 980w, https:\/\/festivaldevitoria.com.br\/conteudo\/uploads\/sites\/24\/2026\/07\/Quase-te-esqueci-2-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minas Gerais \u00e9 representado por<strong> Quase te esqueci<\/strong> <em>(foto acima)<\/em>, dirigido por Raquel Pinheiro, da cantora Julia Branco, que, a partir do uso de fotos anal\u00f3gicas, anima\u00e7\u00e3o e live action, revela o mundo interior da artista onde o cotidiano se abre para pequenas m\u00e1gicas inesperadas. O on\u00edrico tamb\u00e9m se revela em <strong>Planeta Marte<\/strong>, dirigido por Jo\u00e3o Vitor Linhares, do cantor Cesar Soares, do Rio de Janeiro, que mergulha em uma narrativa sensorial sobre amor, ilus\u00e3o e deslocamento emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O videoclipe<strong> A Posse \u00e9 um Fato<\/strong>, dirigido por Murilo Munil e Mar Fagundes, do artista Murilo Munil, retrata o processo de retomada \u00e9tnica atrav\u00e9s da m\u00fasica, recuperando territ\u00f3rios f\u00edsicos e espirituais em Porto Alegre. J\u00e1 <strong>Vida que segue<\/strong>, dirigido por Jo\u00e3o Wainer, do rapper Dexter, \u00e9 um clipe autobiogr\u00e1fico que traz sua hist\u00f3ria pessoal desde o abandono pela m\u00e3e e as consequ\u00eancias do trauma em sua vida, mostrando como o rap e a arte salvaram o cantor da pris\u00e3o do trauma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>33\u00b0 Festival de Cinema de Vit\u00f3ria<\/strong> conta com o patroc\u00ednio da <strong>Petrobras<\/strong> e da <strong>Vale<\/strong> e com o copatroc\u00ednio do <strong>Banestes<\/strong>, atrav\u00e9s da <strong>Lei Rouanet<\/strong>. Conta com o apoio da <strong>TV Gazeta<\/strong>, da <strong>Carla Buaiz Joias<\/strong>, do<strong> Canal Brasil<\/strong>, do <strong>F\u00f3rum dos Festivais<\/strong>, da <strong>Stone Milk<\/strong>, da <strong>Conecta Acessibilidade<\/strong>, da <strong>TVE Esp\u00edrito Santo<\/strong> e do <strong>Canal Like<\/strong>. Conta tamb\u00e9m com o apoio cultural da <strong>Vol Service<\/strong> e a parceria do <strong>Sesc Esp\u00edrito Santo<\/strong>. A realiza\u00e7\u00e3o \u00e9 da <strong>Galp\u00e3o Produ\u00e7\u00f5es<\/strong> e do <strong>Instituto Brasil de Cultura e Arte<\/strong> \u2013 <strong>IBCA<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">33\u00ba Festival de Cinema de Vit\u00f3ria<br><strong><em>10\u00aa Mostra Nacional de Videoclipes<\/em><\/strong><br>Quando: 22 de julho de 2026, 14h<br>Local:\u00a0 Sala Marien Calixte\u00a0 \u2013 Sesc Gl\u00f3ria<br>Entrada Gratuita<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h6 class=\"wp-block-heading\">10\u00aa MOSTRA NACIONAL DE VIDEOCLIPES&nbsp;<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>At\u00e9<\/strong> (Victorhugo Amorim; Taciano Faccini E Gabrielle Nalli. Artista: Ronnie Silveira; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hist\u00f3rias Perif\u00e9ricas<\/strong> (Luan Allen. Artista: Priscila Neres; SE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vida Que Segue<\/strong> (Jo\u00e3o Wainer. Artista: Dexter; SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Epopeia de uma Vida Feliz <\/strong>(Douglas Barros; Artista: Luno Torres; SE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Coco do Recado <\/strong>(Clara Campos E Bianca Bomfim; Artista: Christine Valen\u00e7a &amp; Caetana; PE\/RJ\/BA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Posse \u00e9 um Fato<\/strong> (Murilo Mun\u00ec\u00ed; Mar Fagundes. Artista: Murilo Mun\u00ec\u00ed; RS)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quase Te Esqueci <\/strong>(Raquel Pinheiro. Artista: Julia Branco; MG)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fino Prazer<\/strong> (Tati Rabelo. Artista: Elo\u00e1 Puri; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Astro Rei <\/strong>(Gabriel Uchida; Talita Gusm\u00e3o. Artista: Gabri\u00ea; RO)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Planeta Marte<\/strong> (Jo\u00e3o Vitor Linhares; Z\u00e9ca Vieira. Artista: Cesar Soares ; RJ)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Filtro <\/strong>(Rayan Casagrande; Vinicius Caus. Artista: Inseton; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Monalisa<\/strong> (Lucas S\u00e1. Artista: Frimes; MA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Paladar<\/strong> (Andr\u00e9 Castro Neto. Sthel\u00f4. Artista: Sthel\u00f4; BA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heran\u00e7a<\/strong> (Keila-Sankofa. Artista: Keila-Sankofa; AM)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cana Queimada de Desejos<\/strong> (Ricardo S\u00e9kula; S\u00e1vio Sabi\u00e1. Artista: S\u00e1vio Sabi\u00e1; PE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Telaviva <\/strong>(Rafael Sandim. Artista: Nobat; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dist\u00e2ncia<\/strong> (Daniel Bones. Artista: Laika no Espa\u00e7o; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Presa <\/strong>(Tommy Bellone; Julio Camelo. Artista: Big River; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>T\u00f4 Ligando Pra Nada<\/strong> (Enzo Rodrigues. Artista: Jessica Roberts; ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>sozinho numa bike pra 2<\/strong> (Carlo De C\u00e1sula. Artista: cas\u00fc; ES)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 10\u00aa Mostra Nacional de Videoclipes, que ser\u00e1 realizada no dia 22 de julho, na Sala Marien Calixte (Sesc Gl\u00f3ria), durante o 33\u00ba Festival de Cinema de Vit\u00f3ria, re\u00fane 20 videoclipes de diversos estados brasileiros. O FCV \u00e9 um dos poucos eventos audiovisuais do pa\u00eds a incluir uma janela competitiva exclusiva para videoclipes em seu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[385,3],"tags":[648,383,179,183,35,12,11,185,175,176,188,396,405,167,131],"class_list":["post-71605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-10a-mostra-nacional-de-videoclipes","category-noticias","tag-10a-mostra-nacional-de-videoclipes","tag-33o-festival-de-cinema-de-vitoria","tag-banestes","tag-canal-brasil","tag-curta-metragem","tag-festival-de-cinema","tag-festival-de-cinema-de-vitoria","tag-governo-federal","tag-minc","tag-ministerio-da-cultura","tag-petrobras","tag-tv-gazeta","tag-tve","tag-vale","tag-videoclipes"],"_links":{"self":[{"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/posts\/71605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/comments?post=71605"}],"version-history":[{"count":4,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/posts\/71605\/revisions"}],"predecessor-version":[{"id":71613,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/posts\/71605\/revisions\/71613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/media\/71608"}],"wp:attachment":[{"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/media?parent=71605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/categories?post=71605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/festivaldevitoria.com.br\/33fv\/wp-json\/wp\/v2\/tags?post=71605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}